{"id":6506,"date":"2025-07-02T21:29:43","date_gmt":"2025-07-02T21:29:43","guid":{"rendered":"https:\/\/bonitopack.com\/?p=6506"},"modified":"2025-07-14T06:27:24","modified_gmt":"2025-07-14T06:27:24","slug":"o-que-e-cartolina","status":"publish","type":"post","link":"https:\/\/bonitopack.com\/pt\/o-que-e-cartolina\/","title":{"rendered":"O que \u00e9 papel cart\u00e3o? Um guia para iniciantes"},"content":{"rendered":"<p class=\"wp-block-paragraph\">O papel cart\u00e3o \u00e9 um papel grosso e dur\u00e1vel. Ele \u00e9 mais resistente do que o papel comum de impressora. Entretanto, n\u00e3o \u00e9 t\u00e3o espesso quanto o papel\u00e3o. \u00c9 amplamente usado em artesanato, cart\u00f5es de visita e convites. Quando voc\u00ea acaba de come\u00e7ar a fazer artesanato ou a imprimir, pode se perguntar: \"O que \u00e9 papel-cart\u00e3o?\" Este guia o ajudar\u00e1 a entend\u00ea-lo facilmente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Significado do papel cart\u00e3o<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Vamos come\u00e7ar com o significado de papel-cart\u00e3o. O papel-cart\u00e3o \u00e9 um papel de alta gramatura, resistente e flex\u00edvel. Normalmente, ele pesa entre 65 lb e 110 lb. O n\u00edvel de espessura aumenta com um n\u00famero maior. Ele acrescenta um toque de luxo e \u00e9 mais dur\u00e1vel do que o papel normal. \u00c9 comum encontrar papel-cart\u00e3o em escrit\u00f3rios, escolas e est\u00fadios de design. Ele \u00e9 usado quando se deseja algo mais dur\u00e1vel do que o papel para c\u00f3pia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Para que serve o papel cart\u00e3o?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Muitas pessoas se perguntam: para que serve o papel cart\u00e3o? A resposta \u00e9 simples. Ele \u00e9 usado para muitas coisas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cart\u00f5es de felicita\u00e7\u00f5es<\/li>\n\n\n\n<li>Convites de casamento<\/li>\n\n\n\n<li>Panfletos<\/li>\n\n\n\n<li>Menus<\/li>\n\n\n\n<li>Cart\u00f5es de visita<\/li>\n\n\n\n<li>O relat\u00f3rio abrange<\/li>\n\n\n\n<li>Scrapbooking<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Os artes\u00e3os adoram o papel-cart\u00e3o porque ele mant\u00e9m sua forma. Ele pode ser dobrado, cortado, impresso ou at\u00e9 mesmo <a href=\"https:\/\/bonitopack.com\/pt\/acabamento\/gravacao-combinada\/\">em relevo<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Usos comuns do papel cardstock<\/h2>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Caso de uso<\/strong><\/td><td><strong>Descri\u00e7\u00e3o<\/strong><\/td><\/tr><tr><td>Cart\u00f5es de felicita\u00e7\u00f5es<\/td><td>Mant\u00e9m bem a cor e a forma<\/td><\/tr><tr><td>Cart\u00f5es de visita<\/td><td>Acabamento espesso e profissional<\/td><\/tr><tr><td>Scrapbooking<\/td><td>Perfeito para p\u00e1ginas decorativas e em camadas<\/td><\/tr><tr><td>Menus<\/td><td>Dur\u00e1vel e f\u00e1cil de imprimir<\/td><\/tr><tr><td>Convites de casamento<\/td><td>Parece premium e tem estilo<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Tipos de papel-cart\u00e3o<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Os cart\u00f5es n\u00e3o s\u00e3o todos iguais. H\u00e1 diferentes tipos de papel-cart\u00e3o para v\u00e1rios usos. Cada um tem uma textura, um acabamento ou uma cor exclusiva. Alguns tipos comuns incluem:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Matte Cardstock:<\/strong> Suave e sem brilho. Excelente para imprimir textos.<br><strong>Cartolina brilhante: <\/strong>Brilhante e reflete a luz. Ideal para imagens.<br><strong>Cartolina texturizada: <\/strong>D\u00e1 um toque especial. Geralmente usado em convites.<br><strong>Cartolina colorida: <\/strong>Dispon\u00edvel em v\u00e1rias tonalidades. Excelente para projetos de artesanato.<br><strong>Cartolina reciclada: <\/strong>Ecologicamente correto e <a href=\"https:\/\/bonitopack.com\/pt\/sustentabilidade\/\">Fabricado com materiais reciclados<\/a>.<br>Ao escolher o tipo, pense em seu projeto. Voc\u00ea quer um acabamento liso ou brilhante? Voc\u00ea precisa escrever ou imprimir nele?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tabela de compara\u00e7\u00e3o de tipos de cartolina<\/h2>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Tipo<\/strong><\/td><td><strong>Textura<\/strong><\/td><td><strong>Uso comum<\/strong><\/td><td><strong>Imprimir<\/strong><\/td><td><strong>Apar\u00eancia<\/strong><\/td><\/tr><tr><td>Fosco<\/td><td>Suave<\/td><td>Cart\u00f5es de visita, card\u00e1pios<\/td><td>Sim<\/td><td>Sem brilho<\/td><\/tr><tr><td>Brilhante<\/td><td>Brilhante<\/td><td>Fotos, capas<\/td><td>Sim<\/td><td>Superf\u00edcie reflexiva<\/td><\/tr><tr><td>Texturizado<\/td><td>R\u00fastico\/Padronizado<\/td><td>Convites, artesanato<\/td><td>Limitada<\/td><td>Acabamento art\u00edstico<\/td><\/tr><tr><td>Colorido<\/td><td>Suave\/Variada<\/td><td>P\u00f4steres, placas<\/td><td>Sim<\/td><td>Cores vibrantes<\/td><\/tr><tr><td>Reciclado<\/td><td>\u00c1spero<\/td><td>Projetos ecol\u00f3gicos<\/td><td>Sim<\/td><td>Tons naturais<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">O que \u00e9 a Coverstock?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Agora vamos responder a outra pergunta comum: o que \u00e9 covertock? Coverstock \u00e9 semelhante ao papel cart\u00e3o. De fato, algumas pessoas usam os termos de forma intercambi\u00e1vel. Mas, tecnicamente, o covertock \u00e9 um pouco mais pesado. Geralmente \u00e9 usado para capas de livretos ou relat\u00f3rios. O papel de capa geralmente tem um acabamento mais suave. Ele \u00e9 apresentado de forma polida. Quando voc\u00ea precisa de uma apar\u00eancia limpa e profissional, o covertock funciona. Ele tamb\u00e9m est\u00e1 dispon\u00edvel em acabamentos fosco, brilhante ou texturizado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Diferen\u00e7a entre cardstock e coverstock<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">H\u00e1 uma diferen\u00e7a pequena, mas importante, entre a cartolina e a capa. A cartolina \u00e9 um pouco mais leve e mais flex\u00edvel. A capa \u00e9 mais grossa e mais resistente. Talvez voc\u00ea n\u00e3o perceba uma grande diferen\u00e7a s\u00f3 de olhar. Mas, ao imprimir ou dobrar, voc\u00ea sentir\u00e1 a mudan\u00e7a. Aqui est\u00e1 um resumo r\u00e1pido:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A cartolina \u00e9 \u00f3tima para artesanato e impress\u00e3o em geral.<\/li>\n\n\n\n<li>O Coverstock \u00e9 ideal para capas dur\u00e1veis ou impress\u00f5es de alta qualidade.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ambos v\u00eam em v\u00e1rias cores, tamanhos e acabamentos. Escolha a que melhor se adapta ao seu projeto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como o papel cart\u00e3o \u00e9 medido<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O estoque de cart\u00f5es \u00e9 geralmente medido em libras (lb) ou GSM (gramas por metro quadrado). Os usu\u00e1rios dos EUA geralmente o veem em libras. Os usu\u00e1rios europeus costumam usar <a href=\"https:\/\/en.wikipedia.org\/wiki\/GSM\">GSM<\/a>. A gramatura indica a espessura ou o peso do papel.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>65 lb (176 GSM) <\/strong>- Papel cart\u00e3o leve, bom para impress\u00e3o<\/li>\n\n\n\n<li><strong>80 lb (216 GSM) <\/strong>- M\u00e9dio, adequado para cart\u00f5es<\/li>\n\n\n\n<li><strong>100 lb (270 GSM)<\/strong> - Pesado, para convites grossos<\/li>\n\n\n\n<li><strong>110 lb (298 GSM) <\/strong>- Muito pesado, quase como um papel\u00e3o fino<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Quanto maior a gramatura, mais espesso e resistente \u00e9 o papel.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Dicas para usar cartolina<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Caso deseje imprimir em papel cart\u00e3o, verifique se sua impressora pode lidar com isso. As impressoras a laser geralmente reagem melhor a pap\u00e9is mais grossos do que as impressoras a jato de tinta. Sempre teste uma folha antes de imprimir um lote. Como cortar cartolina? Use uma faca de artesanato ou um cortador de papel para obter bordas limpas. Se for dobrar, use um dobrador de ossos ou uma ferramenta de pontua\u00e7\u00e3o. Isso evita rachaduras. Para escrever, use canetas esferogr\u00e1ficas ou de gel. Algumas tintas podem borrar no papel cart\u00e3o brilhante.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Por que o papel cart\u00e3o \u00e9 importante<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O papel cart\u00e3o oferece durabilidade e um toque premium. N\u00e3o importa se voc\u00ea est\u00e1 simplesmente imprimindo um convite de casamento ou se est\u00e1 fazendo artesanato em casa, ele tem valor. \u00c9 barato, pode ser comprado em uma loja ou on-line e \u00e9 simples de operar. Devido \u00e0 sua flexibilidade, h\u00e1 cada vez mais pessoas usando papel-cart\u00e3o para fins comerciais e pessoais. Ele est\u00e1 entre o papel fino e o papel\u00e3o s\u00f3lido.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclus\u00e3o<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O que \u00e9 papel-cart\u00e3o? \u00c9 um papel resistente e dur\u00e1vel, bom para impress\u00e3o, artesanato e apresenta\u00e7\u00e3o. \u00c9 inquebr\u00e1vel, muito confi\u00e1vel e est\u00e1 dispon\u00edvel em v\u00e1rios estilos. Voc\u00ea tamb\u00e9m j\u00e1 sabe para que o papel cart\u00e3o \u00e9 usado, a diferen\u00e7a entre cart\u00e3o e capa e examinou os tipos de cart\u00e3o. O papel-cart\u00e3o o ajudar\u00e1 a dar uma apar\u00eancia especial ao seu projeto, quer voc\u00ea esteja criando um convite sofisticado ou um panfleto b\u00e1sico. Selecione a gramatura, a textura e o acabamento adequados que aumentem a criatividade.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Perguntas frequentes<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Para que \u00e9 usado o papel cart\u00e3o?<\/strong><strong><br><\/strong>O papel cart\u00e3o \u00e9 usado para artesanato, convites, card\u00e1pios e cart\u00f5es de visita. \u00c9 mais resistente do que o papel comum e f\u00e1cil de imprimir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>O papel cart\u00e3o \u00e9 o mesmo que o papel de capa?<\/strong><strong><br><\/strong>Eles s\u00e3o semelhantes, mas o papel de capa geralmente \u00e9 mais pesado e mais polido. O papel cart\u00e3o \u00e9 mais flex\u00edvel e usado para projetos gerais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Posso imprimir em papel cart\u00e3o com uma impressora dom\u00e9stica?<br><\/strong>Sim, muitas impressoras dom\u00e9sticas aceitam papel cart\u00e3o. Basta verificar o limite de peso antes de imprimir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Card stock is a thick, durable paper. It is stronger than regular printer paper. However it is not as thick as cardboard. It is widely used in crafts, business cards as well as invitations. When you have just begun crafting or printing, you may ask, \u201cWhat is card stock?\u201d This guide will help you understand [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6736,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_titles_title":"What is Card Stock? A Beginner-Friendly Guide","_seopress_titles_desc":"Thick, durable paper perfect for crafts, cards, and prints. Learn what is card stock, its uses, types, and how it differs from coverstock.\n","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"card stock","footnotes":""},"categories":[40],"tags":[],"class_list":["post-6506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-packaging"],"acf":[],"_links":{"self":[{"href":"https:\/\/bonitopack.com\/pt\/wp-json\/wp\/v2\/posts\/6506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bonitopack.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bonitopack.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bonitopack.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/bonitopack.com\/pt\/wp-json\/wp\/v2\/comments?post=6506"}],"version-history":[{"count":0,"href":"https:\/\/bonitopack.com\/pt\/wp-json\/wp\/v2\/posts\/6506\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bonitopack.com\/pt\/wp-json\/wp\/v2\/media\/6736"}],"wp:attachment":[{"href":"https:\/\/bonitopack.com\/pt\/wp-json\/wp\/v2\/media?parent=6506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bonitopack.com\/pt\/wp-json\/wp\/v2\/categories?post=6506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bonitopack.com\/pt\/wp-json\/wp\/v2\/tags?post=6506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}